{"id":98434,"date":"2026-01-23T11:38:50","date_gmt":"2026-01-23T16:38:50","guid":{"rendered":"https:\/\/www.evafm.net\/sitio\/?p=98434"},"modified":"2026-01-23T12:42:23","modified_gmt":"2026-01-23T17:42:23","slug":"emelec-pago-y-evito-nuevas-sanciones-deportivas","status":"publish","type":"post","link":"https:\/\/www.evafm.net\/sitio\/emelec-pago-y-evito-nuevas-sanciones-deportivas\/","title":{"rendered":"Emelec pag\u00f3 y evit\u00f3 nuevas sanciones deportivas"},"content":{"rendered":"<p>El\u00a0<a href=\"https:\/\/www.ecuavisa.com\/deportes\/emelec\" target=\"_blank\" rel=\"noopener\"><strong>Club Sport Emelec\u00a0<\/strong><\/a>anunci\u00f3 este viernes la cancelaci\u00f3n de todas sus deudas programadas hasta el<strong> 23 de enero<\/strong> a las\u00a0<strong>17h00<\/strong>, como parte de un plan de ordenamiento financiero en medio del proceso de intervenci\u00f3n que atraviesa la instituci\u00f3n.<\/p>\n<p>Seg\u00fan el comunicado oficial, la medida busca cumplir con las obligaciones pendientes, fortalecer la estabilidad administrativa del club y sentar bases s\u00f3lidas para su futuro, tanto en lo dirigencial como en lo deportivo.<\/p>\n<p>\u201cEstas acciones forman parte del compromiso institucional del club por cumplir con sus obligaciones, fortalecer su estabilidad administrativa y continuar trabajando en beneficio de la instituci\u00f3n y de su futuro deportivo\u201d, se\u00f1ala el documento.<\/p>\n<p>La cancelaci\u00f3n de estas deudas se convierte en un paso clave dentro del proceso de reestructuraci\u00f3n interna, con el objetivo de generar confianza entre hinchas, acreedores y el entorno futbol\u00edstico, devolviendo tranquilidad a un club que atraviesa un periodo sensible a nivel financiero y administrativo<strong>.(D)<\/strong><\/p>\n<div class=\"css-175oi2r r-18u37iz r-136ojw6\">\n<div class=\"css-175oi2r r-1iusvr4 r-16y2uox r-1777fci\">\n<div class=\"css-175oi2r r-zl2h9q\">\n<div class=\"css-175oi2r r-k4xj1c r-18u37iz r-1wtj0ep\">\n<div class=\"css-175oi2r r-1d09ksm r-18u37iz r-1wbh5a2\">\n<div class=\"css-175oi2r r-1wbh5a2 r-dnmrzs r-1ny4l3l\">\n<div id=\"id__x01lm4k3sx\" class=\"css-175oi2r r-1wbh5a2 r-dnmrzs r-1ny4l3l\" data-testid=\"User-Name\">\n<div class=\"css-175oi2r r-1awozwy r-18u37iz r-1wbh5a2 r-dnmrzs\">\n<div class=\"css-175oi2r r-1wbh5a2 r-dnmrzs\">\n<div class=\"css-175oi2r r-1awozwy r-18u37iz r-1wbh5a2 r-dnmrzs\">\n<div class=\"css-146c3p1 r-bcqeeo r-1ttztb7 r-qvutc0 r-37j5jr r-a023e6 r-rjixqe r-b88u0q r-1awozwy r-6koalj r-1udh08x r-3s2u2q\" dir=\"ltr\"><strong><span class=\"css-1jxf684 r-dnmrzs r-1udh08x r-1udbk01 r-3s2u2q r-bcqeeo r-1ttztb7 r-qvutc0 r-poiln3\"><span class=\"css-1jxf684 r-bcqeeo r-1ttztb7 r-qvutc0 r-poiln3\">Club Sport Emelec<\/span><\/span><\/strong><\/div>\n<div class=\"css-146c3p1 r-bcqeeo r-1ttztb7 r-qvutc0 r-37j5jr r-a023e6 r-rjixqe r-16dba41 r-xoduu5 r-18u37iz r-1q142lx\" dir=\"ltr\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"css-175oi2r r-18u37iz r-1wbh5a2\">\n<div class=\"css-175oi2r r-1d09ksm r-18u37iz r-1wbh5a2\">\n<div class=\"css-175oi2r r-1wbh5a2 r-dnmrzs\">\n<div class=\"css-146c3p1 r-dnmrzs r-1udh08x r-1udbk01 r-3s2u2q r-bcqeeo r-1ttztb7 r-qvutc0 r-37j5jr r-a023e6 r-rjixqe r-16dba41 r-18u37iz r-1wvb978\" dir=\"ltr\"><strong><span class=\"css-1jxf684 r-bcqeeo r-1ttztb7 r-qvutc0 r-poiln3\">@CSEmelec<\/span><\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"css-175oi2r r-1kkk96v\">\n<div class=\"css-175oi2r r-1awozwy r-18u37iz r-1cmwbt1 r-1wtj0ep\">\n<div class=\"css-175oi2r r-18u37iz r-1h0z5md\"><\/div>\n<div class=\"css-175oi2r r-1awozwy r-6koalj r-18u37iz\">\n<div class=\"css-175oi2r\">\n<div class=\"css-175oi2r r-18u37iz r-1h0z5md\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"css-175oi2r\">\n<div class=\"css-175oi2r\">\n<div class=\"css-175oi2r r-1s2bzr4\">\n<div id=\"id__k3koxl0ic4\" class=\"css-146c3p1 r-bcqeeo r-1ttztb7 r-qvutc0 r-37j5jr r-1inkyih r-16dba41 r-bnwqim r-135wba7\" dir=\"auto\" lang=\"pt\" data-testid=\"tweetText\"><strong><span class=\"css-1jxf684 r-bcqeeo r-1ttztb7 r-qvutc0 r-poiln3\"> Comunicado Oficial<\/span><\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/G_Wm2mmWcAAlzBu?format=jpg&amp;name=small\" alt=\"Imagen\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:<\/strong> evafm.net &#8211; ecuavisa.com<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"deportes-ecuador,general\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1769168330\"\r\n\t            data-title=\"Emelec pag\u00f3 y evit\u00f3 nuevas sanciones deportivas\" \r\n\t            data-home=\"https:\/\/www.evafm.net\/sitio\"><\/div>","protected":false},"excerpt":{"rendered":"<p>El\u00a0Club Sport Emelec\u00a0anunci\u00f3 este viernes la cancelaci\u00f3n de todas sus deudas programadas hasta el 23 de enero a las\u00a017h00, como parte de un plan de ordenamiento financiero en medio del proceso de intervenci\u00f3n que atraviesa la instituci\u00f3n. Seg\u00fan el comunicado oficial, la medida busca cumplir con las obligaciones pendientes, fortalecer la estabilidad administrativa del club&#8230;<\/p>\n","protected":false},"author":5,"featured_media":98435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1557,1720],"tags":[],"class_list":["post-98434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes-ecuador","category-general","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/posts\/98434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/comments?post=98434"}],"version-history":[{"count":2,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/posts\/98434\/revisions"}],"predecessor-version":[{"id":98446,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/posts\/98434\/revisions\/98446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/media\/98435"}],"wp:attachment":[{"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/media?parent=98434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/categories?post=98434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evafm.net\/sitio\/wp-json\/wp\/v2\/tags?post=98434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}